{"id":119,"count":1,"description":"","link":"https:\/\/cotalba.es\/en\/category\/2025-en\/","name":"2025","slug":"2025-en","taxonomy":"category","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>2025 archivos - Monasterio de Sant Jeroni de Cotalba<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cotalba.es\/en\/category\/2025-en\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"2025 archivos - Monasterio de Sant Jeroni de Cotalba\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cotalba.es\/en\/category\/2025-en\/\" \/>\n<meta property=\"og:site_name\" content=\"Monasterio de Sant Jeroni de Cotalba\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/cotalba.es\\\/en\\\/category\\\/2025-en\\\/\",\"url\":\"https:\\\/\\\/cotalba.es\\\/en\\\/category\\\/2025-en\\\/\",\"name\":\"2025 archivos - Monasterio de Sant Jeroni de Cotalba\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cotalba.es\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cotalba.es\\\/en\\\/category\\\/2025-en\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cotalba.es\\\/en\\\/category\\\/2025-en\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/cotalba.es\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"2025\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cotalba.es\\\/#website\",\"url\":\"https:\\\/\\\/cotalba.es\\\/\",\"name\":\"Monasterio de Sant Jeroni de Cotalba\",\"description\":\"Monasterio de Sant Jeroni de Cotalba\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cotalba.es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"2025 archivos - Monasterio de Sant Jeroni de Cotalba","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cotalba.es\/en\/category\/2025-en\/","og_locale":"en_US","og_type":"article","og_title":"2025 archivos - Monasterio de Sant Jeroni de Cotalba","og_url":"https:\/\/cotalba.es\/en\/category\/2025-en\/","og_site_name":"Monasterio de Sant Jeroni de Cotalba","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/cotalba.es\/en\/category\/2025-en\/","url":"https:\/\/cotalba.es\/en\/category\/2025-en\/","name":"2025 archivos - Monasterio de Sant Jeroni de Cotalba","isPartOf":{"@id":"https:\/\/cotalba.es\/#website"},"breadcrumb":{"@id":"https:\/\/cotalba.es\/en\/category\/2025-en\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/cotalba.es\/en\/category\/2025-en\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/cotalba.es\/en\/"},{"@type":"ListItem","position":2,"name":"2025"}]},{"@type":"WebSite","@id":"https:\/\/cotalba.es\/#website","url":"https:\/\/cotalba.es\/","name":"Monasterio de Sant Jeroni de Cotalba","description":"Monasterio de Sant Jeroni de Cotalba","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cotalba.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/cotalba.es\/en\/wp-json\/wp\/v2\/categories\/119","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cotalba.es\/en\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/cotalba.es\/en\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/cotalba.es\/en\/wp-json\/wp\/v2\/posts?categories=119"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}