{"id":9004,"date":"2019-05-31T09:55:56","date_gmt":"2019-05-31T09:55:56","guid":{"rendered":"https:\/\/cotalba.es\/?page_id=9004"},"modified":"2021-09-21T19:39:43","modified_gmt":"2021-09-21T19:39:43","slug":"lower-cloister","status":"publish","type":"page","link":"https:\/\/cotalba.es\/en\/internal-architecture\/lower-cloister\/","title":{"rendered":"Lower cloister"},"content":{"rendered":"[vc_row type=&#8221;full_width_content&#8221; full_screen_row_position=&#8221;middle&#8221; bg_image=&#8221;7642&#8243; bg_position=&#8221;center bottom&#8221; bg_repeat=&#8221;no-repeat&#8221; parallax_bg=&#8221;true&#8221; parallax_bg_speed=&#8221;medium&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; top_padding=&#8221;200&#8243; bottom_padding=&#8221;200&#8243; overlay_strength=&#8221;0.3&#8243; shape_divider_position=&#8221;bottom&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;padding-10-percent&#8221; column_padding_position=&#8221;left-right&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_link_target=&#8221;_self&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_row_inner equal_height=&#8221;yes&#8221; content_placement=&#8221;middle&#8221; column_margin=&#8221;default&#8221; text_align=&#8221;left&#8221;][vc_column_inner column_padding=&#8221;padding-5-percent&#8221; column_padding_position=&#8221;all&#8221; background_color=&#8221;#1d0e00&#8243; background_color_opacity=&#8221;0.6&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; width=&#8221;2\/3&#8243; tablet_width_inherit=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_custom_heading text=&#8221;Lower cloister&#8221; font_container=&#8221;tag:h1|text_align:left|color:%23ffffff&#8221; use_theme_fonts=&#8221;yes&#8221;][vc_custom_heading text=&#8221;A structure that makes up the backbone of any monastery complex, around which the different buildings are distributed.&#8221; font_container=&#8221;tag:h4|text_align:left|color:%23ffffff&#8221; use_theme_fonts=&#8221;yes&#8221;][\/vc_column_inner][vc_column_inner column_padding=&#8221;padding-5-percent&#8221; column_padding_position=&#8221;left-right&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; width=&#8221;1\/3&#8243; tablet_width_inherit=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_content&#8221; full_screen_row_position=&#8221;middle&#8221; equal_height=&#8221;yes&#8221; content_placement=&#8221;top&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; top_padding=&#8221;60&#8243; class=&#8221;colum-destok&#8221; overlay_strength=&#8221;0.3&#8243; shape_divider_position=&#8221;bottom&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;padding-5-percent&#8221; column_padding_position=&#8221;left-right&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_link_target=&#8221;_self&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_row_inner equal_height=&#8221;yes&#8221; content_placement=&#8221;top&#8221; column_margin=&#8221;default&#8221; text_align=&#8221;left&#8221;][vc_column_inner column_padding=&#8221;padding-5-percent&#8221; column_padding_position=&#8221;left-right&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][nectar_btn size=&#8221;large&#8221; open_new_tab=&#8221;true&#8221; button_style=&#8221;regular&#8221; button_color_2=&#8221;Accent-Color&#8221; icon_family=&#8221;none&#8221; url=&#8221;https:\/\/www.mgticket.com\/cotalba\/public\/janto\/&#8221; text=&#8221;Buy ticket&#8221; margin_top=&#8221;30&#8243;][\/vc_column_inner][vc_column_inner column_padding=&#8221;padding-5-percent&#8221; column_padding_position=&#8221;left-right&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; top_margin=&#8221;-150&#8243; column_link_target=&#8221;_self&#8221; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_raw_html]JTNDaWZyYW1lJTIwc3JjJTNEJTIyaHR0cHMlM0ElMkYlMkZ3d3cuZ29vZ2xlLmNvbSUyRm1hcHMlMkZlbWJlZCUzRnBiJTNEJTIxMW0wJTIxM20yJTIxMXNlcyUyMTJzdXMlMjE0djE0NjczNzc4MDE2NjUlMjE2bTglMjExbTclMjExc240UnF1Nm5Rd1BnQUFBUXZPejF4cXclMjEybTIlMjExZDM4Ljk0MDUzNTg2MzA0MjQ2JTIxMmQtMC4yNDU5ODY2OTAyODM5ODQ5JTIxM2YzMDMuNzY3NDMwMjc0Mjk0JTIxNGYzLjA2NzIxMzcyMTg4NTAzOTUlMjE1ZjAuNDAwMDAwMDAwMDAwMDAwMiUyMiUyMHdpZHRoJTNEJTIyMTAwJTI1JTIyJTIwaGVpZ2h0JTNEJTIyNTAwJTIyJTIwZnJhbWVib3JkZXIlM0QlMjIwJTIyJTIwc3R5bGUlM0QlMjJib3JkZXIlM0EwJTIyJTIwYWxsb3dmdWxsc2NyZWVuJTNEJTIyJTIyJTNFJTNDJTJGaWZyYW1lJTNF[\/vc_raw_html][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_content&#8221; full_screen_row_position=&#8221;middle&#8221; equal_height=&#8221;yes&#8221; content_placement=&#8221;top&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; top_padding=&#8221;30&#8243; class=&#8221;colum-mobile&#8221; overlay_strength=&#8221;0.3&#8243; shape_divider_position=&#8221;bottom&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;padding-5-percent&#8221; column_padding_position=&#8221;left-right&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_link_target=&#8221;_self&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_row_inner equal_height=&#8221;yes&#8221; content_placement=&#8221;middle&#8221; column_margin=&#8221;default&#8221; text_align=&#8221;left&#8221;][vc_column_inner column_padding=&#8221;padding-5-percent&#8221; column_padding_position=&#8221;left-right&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; top_margin=&#8221;-150&#8243; column_link_target=&#8221;_self&#8221; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_raw_html]JTNDaWZyYW1lJTIwc3JjJTNEJTIyaHR0cHMlM0ElMkYlMkZ3d3cuZ29vZ2xlLmNvbSUyRm1hcHMlMkZlbWJlZCUzRnBiJTNEJTIxMW0wJTIxM20yJTIxMXNlcyUyMTJzdXMlMjE0djE0NjczNzc4MDE2NjUlMjE2bTglMjExbTclMjExc240UnF1Nm5Rd1BnQUFBUXZPejF4cXclMjEybTIlMjExZDM4Ljk0MDUzNTg2MzA0MjQ2JTIxMmQtMC4yNDU5ODY2OTAyODM5ODQ5JTIxM2YzMDMuNzY3NDMwMjc0Mjk0JTIxNGYzLjA2NzIxMzcyMTg4NTAzOTUlMjE1ZjAuNDAwMDAwMDAwMDAwMDAwMiUyMiUyMHdpZHRoJTNEJTIyMTAwJTI1JTIyJTIwaGVpZ2h0JTNEJTIyNTAwJTIyJTIwZnJhbWVib3JkZXIlM0QlMjIwJTIyJTIwc3R5bGUlM0QlMjJib3JkZXIlM0EwJTIyJTIwYWxsb3dmdWxsc2NyZWVuJTNEJTIyJTIyJTNFJTNDJTJGaWZyYW1lJTNF[\/vc_raw_html][\/vc_column_inner][vc_column_inner column_padding=&#8221;padding-5-percent&#8221; column_padding_position=&#8221;left-right&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; top_margin=&#8221;30&#8243; column_link_target=&#8221;_self&#8221; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][nectar_btn size=&#8221;large&#8221; open_new_tab=&#8221;true&#8221; button_style=&#8221;regular&#8221; button_color_2=&#8221;Accent-Color&#8221; icon_family=&#8221;none&#8221; url=&#8221;https:\/\/www.mgticket.com\/cotalba\/public\/janto\/&#8221; text=&#8221;Buy ticket&#8221; margin_top=&#8221;30&#8243;][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_content&#8221; full_screen_row_position=&#8221;middle&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; top_padding=&#8221;60&#8243; overlay_strength=&#8221;0.3&#8243; shape_divider_position=&#8221;bottom&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;padding-10-percent&#8221; column_padding_position=&#8221;left-right&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_link_target=&#8221;_self&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_row_inner column_margin=&#8221;default&#8221; text_align=&#8221;left&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_position=&#8221;all&#8221; background_color=&#8221;#ffffff&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; bottom_margin=&#8221;100&#8243; column_link_target=&#8221;_self&#8221; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_gallery type=&#8221;flickity_style&#8221; images=&#8221;7643,7644,7731,7732,8362,8363,8364,8365&#8243; flickity_controls=&#8221;pagination&#8221; flickity_desktop_columns=&#8221;1&#8243; flickity_small_desktop_columns=&#8221;1&#8243; flickity_tablet_columns=&#8221;1&#8243; flickity_box_shadow=&#8221;none&#8221; onclick=&#8221;link_image&#8221; img_size=&#8221;600&#215;400&#8243;][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_content&#8221; full_screen_row_position=&#8221;middle&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; overlay_strength=&#8221;0.3&#8243; shape_divider_position=&#8221;bottom&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;padding-10-percent&#8221; column_padding_position=&#8221;left-right&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_link_target=&#8221;_self&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_row_inner column_margin=&#8221;default&#8221; top_padding=&#8221;30&#8243; text_align=&#8221;left&#8221;][vc_column_inner column_padding=&#8221;padding-5-percent&#8221; column_padding_position=&#8221;right&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_column_text]A structure that makes up the backbone of any monastery complex, around which the different buildings are distributed.<\/p>\n<p>Four galleries made up of two superimposed levels can be found at Sant Jeroni. The lower part dates back to the beginnings of the monastery in the 14th and 15th centuries, whereas the upper galleries were constructed in different stages between the 15th and 18th centuries.<\/p>\n<p>Seven vaults were constructed in each of the galleries of the upper and lower cloisters, plus one at each corner.<\/p>\n<p>A feature that is peculiar to the lower cloister is that both the ribs of the vaults and the ogival arches are constructed from bricks and lime mortar, in Moorish style. The natural colour of the bricks is combined with white, creating a very singular two-colour appearance. Stone is used for the bases of the arches and the keystones. It is an open space with ribs.[\/vc_column_text][\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_position=&#8221;all&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_column_text]A highlight in the south-east corner is a unique spiral staircase in Gothic-Flamenco style, alongside which can be seen a space marked out in moulding, an imprint of the location of one of the paintings of &#8220;The Seasons&#8221; done by Father Borr\u00e1s; the remaining three paintings would have been located in the other corners of the cloister.<\/p>\n<p>The four galleries make up a central patio known as the &#8220;Orange Tree Patio&#8221;, in which can be found a well that dates back to the origin of the monastery, and a pool for water storage with 24 small fountains, whose construction was ordered by Mar\u00eda Enr\u00edquez de Luna in the 16th century.<\/p>\n<p>The plant decoration in this patio consists of orange trees, a 60 foot high date palm and two smaller palms, all of which are framed by bushes.[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row]\n","protected":false},"excerpt":{"rendered":"<p>[vc_row type=&#8221;full_width_content&#8221; full_screen_row_position=&#8221;middle&#8221; bg_image=&#8221;7642&#8243; bg_position=&#8221;center bottom&#8221; bg_repeat=&#8221;no-repeat&#8221; parallax_bg=&#8221;true&#8221; parallax_bg_speed=&#8221;medium&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; top_padding=&#8221;200&#8243; bottom_padding=&#8221;200&#8243; overlay_strength=&#8221;0.3&#8243; shape_divider_position=&#8221;bottom&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;padding-10-percent&#8221; column_padding_position=&#8221;left-right&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_link_target=&#8221;_self&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_row_inner equal_height=&#8221;yes&#8221; content_placement=&#8221;middle&#8221; column_margin=&#8221;default&#8221; text_align=&#8221;left&#8221;][vc_column_inner column_padding=&#8221;padding-5-percent&#8221; column_padding_position=&#8221;all&#8221; background_color=&#8221;#1d0e00&#8243; background_color_opacity=&#8221;0.6&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; width=&#8221;2\/3&#8243; tablet_width_inherit=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_custom_heading text=&#8221;Lower cloister&#8221; font_container=&#8221;tag:h1|text_align:left|color:%23ffffff&#8221; use_theme_fonts=&#8221;yes&#8221;][vc_custom_heading&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":9188,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-9004","page","type-page","status-publish"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Lower cloister - Monasterio de Sant Jeroni de Cotalba<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cotalba.es\/en\/internal-architecture\/lower-cloister\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Lower cloister - Monasterio de Sant Jeroni de Cotalba\" \/>\n<meta property=\"og:description\" content=\"[vc_row type=&#8221;full_width_content&#8221; full_screen_row_position=&#8221;middle&#8221; bg_image=&#8221;7642&#8243; bg_position=&#8221;center bottom&#8221; bg_repeat=&#8221;no-repeat&#8221; parallax_bg=&#8221;true&#8221; parallax_bg_speed=&#8221;medium&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; top_padding=&#8221;200&#8243; bottom_padding=&#8221;200&#8243; overlay_strength=&#8221;0.3&#8243; shape_divider_position=&#8221;bottom&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;padding-10-percent&#8221; column_padding_position=&#8221;left-right&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_link_target=&#8221;_self&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_row_inner equal_height=&#8221;yes&#8221; content_placement=&#8221;middle&#8221; column_margin=&#8221;default&#8221; text_align=&#8221;left&#8221;][vc_column_inner column_padding=&#8221;padding-5-percent&#8221; column_padding_position=&#8221;all&#8221; background_color=&#8221;#1d0e00&#8243; background_color_opacity=&#8221;0.6&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; width=&#8221;2\/3&#8243; tablet_width_inherit=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_custom_heading text=&#8221;Lower cloister&#8221; font_container=&#8221;tag:h1|text_align:left|color:%23ffffff&#8221; use_theme_fonts=&#8221;yes&#8221;][vc_custom_heading...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cotalba.es\/en\/internal-architecture\/lower-cloister\/\" \/>\n<meta property=\"og:site_name\" content=\"Monasterio de Sant Jeroni de Cotalba\" \/>\n<meta property=\"article:modified_time\" content=\"2021-09-21T19:39:43+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"8 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cotalba.es\\\/en\\\/internal-architecture\\\/lower-cloister\\\/\",\"url\":\"https:\\\/\\\/cotalba.es\\\/en\\\/internal-architecture\\\/lower-cloister\\\/\",\"name\":\"Lower cloister - Monasterio de Sant Jeroni de Cotalba\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cotalba.es\\\/#website\"},\"datePublished\":\"2019-05-31T09:55:56+00:00\",\"dateModified\":\"2021-09-21T19:39:43+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cotalba.es\\\/en\\\/internal-architecture\\\/lower-cloister\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cotalba.es\\\/en\\\/internal-architecture\\\/lower-cloister\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cotalba.es\\\/en\\\/internal-architecture\\\/lower-cloister\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/cotalba.es\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Internal architecture\",\"item\":\"https:\\\/\\\/cotalba.es\\\/en\\\/internal-architecture\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Lower cloister\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cotalba.es\\\/#website\",\"url\":\"https:\\\/\\\/cotalba.es\\\/\",\"name\":\"Monasterio de Sant Jeroni de Cotalba\",\"description\":\"Monasterio de Sant Jeroni de Cotalba\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cotalba.es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Lower cloister - Monasterio de Sant Jeroni de Cotalba","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cotalba.es\/en\/internal-architecture\/lower-cloister\/","og_locale":"en_US","og_type":"article","og_title":"Lower cloister - Monasterio de Sant Jeroni de Cotalba","og_description":"[vc_row type=&#8221;full_width_content&#8221; full_screen_row_position=&#8221;middle&#8221; bg_image=&#8221;7642&#8243; bg_position=&#8221;center bottom&#8221; bg_repeat=&#8221;no-repeat&#8221; parallax_bg=&#8221;true&#8221; parallax_bg_speed=&#8221;medium&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; top_padding=&#8221;200&#8243; bottom_padding=&#8221;200&#8243; overlay_strength=&#8221;0.3&#8243; shape_divider_position=&#8221;bottom&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;padding-10-percent&#8221; column_padding_position=&#8221;left-right&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_link_target=&#8221;_self&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_row_inner equal_height=&#8221;yes&#8221; content_placement=&#8221;middle&#8221; column_margin=&#8221;default&#8221; text_align=&#8221;left&#8221;][vc_column_inner column_padding=&#8221;padding-5-percent&#8221; column_padding_position=&#8221;all&#8221; background_color=&#8221;#1d0e00&#8243; background_color_opacity=&#8221;0.6&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; width=&#8221;2\/3&#8243; tablet_width_inherit=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_custom_heading text=&#8221;Lower cloister&#8221; font_container=&#8221;tag:h1|text_align:left|color:%23ffffff&#8221; use_theme_fonts=&#8221;yes&#8221;][vc_custom_heading...","og_url":"https:\/\/cotalba.es\/en\/internal-architecture\/lower-cloister\/","og_site_name":"Monasterio de Sant Jeroni de Cotalba","article_modified_time":"2021-09-21T19:39:43+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"8 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/cotalba.es\/en\/internal-architecture\/lower-cloister\/","url":"https:\/\/cotalba.es\/en\/internal-architecture\/lower-cloister\/","name":"Lower cloister - Monasterio de Sant Jeroni de Cotalba","isPartOf":{"@id":"https:\/\/cotalba.es\/#website"},"datePublished":"2019-05-31T09:55:56+00:00","dateModified":"2021-09-21T19:39:43+00:00","breadcrumb":{"@id":"https:\/\/cotalba.es\/en\/internal-architecture\/lower-cloister\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cotalba.es\/en\/internal-architecture\/lower-cloister\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/cotalba.es\/en\/internal-architecture\/lower-cloister\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/cotalba.es\/en\/"},{"@type":"ListItem","position":2,"name":"Internal architecture","item":"https:\/\/cotalba.es\/en\/internal-architecture\/"},{"@type":"ListItem","position":3,"name":"Lower cloister"}]},{"@type":"WebSite","@id":"https:\/\/cotalba.es\/#website","url":"https:\/\/cotalba.es\/","name":"Monasterio de Sant Jeroni de Cotalba","description":"Monasterio de Sant Jeroni de Cotalba","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cotalba.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/cotalba.es\/en\/wp-json\/wp\/v2\/pages\/9004","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cotalba.es\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/cotalba.es\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/cotalba.es\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/cotalba.es\/en\/wp-json\/wp\/v2\/comments?post=9004"}],"version-history":[{"count":3,"href":"https:\/\/cotalba.es\/en\/wp-json\/wp\/v2\/pages\/9004\/revisions"}],"predecessor-version":[{"id":12651,"href":"https:\/\/cotalba.es\/en\/wp-json\/wp\/v2\/pages\/9004\/revisions\/12651"}],"up":[{"embeddable":true,"href":"https:\/\/cotalba.es\/en\/wp-json\/wp\/v2\/pages\/9188"}],"wp:attachment":[{"href":"https:\/\/cotalba.es\/en\/wp-json\/wp\/v2\/media?parent=9004"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}