{"id":9724,"date":"2019-06-13T16:10:22","date_gmt":"2019-06-13T16:10:22","guid":{"rendered":"https:\/\/cotalba.es\/12a-edicion-ciclo-conciertos-del-monasterio-de-sant-jeroni-de-cotalba\/"},"modified":"2020-05-27T10:44:40","modified_gmt":"2020-05-27T10:44:40","slug":"12a-edicion-ciclo-conciertos-del-monasterio-de-sant-jeroni-de-cotalba","status":"publish","type":"post","link":"https:\/\/cotalba.es\/fr\/12a-edicion-ciclo-conciertos-del-monasterio-de-sant-jeroni-de-cotalba\/","title":{"rendered":"12\u00aa edici\u00f3n ciclo conciertos del Monasterio de Sant Jeroni de Cotalba"},"content":{"rendered":"[vc_row type=\u00a0\u00bbin_container\u00a0\u00bb full_screen_row_position=\u00a0\u00bbmiddle\u00a0\u00bb scene_position=\u00a0\u00bbcenter\u00a0\u00bb text_color=\u00a0\u00bbdark\u00a0\u00bb text_align=\u00a0\u00bbleft\u00a0\u00bb overlay_strength=\u00a0\u00bb0.3&Prime; shape_divider_position=\u00a0\u00bbbottom\u00a0\u00bb][vc_column column_padding=\u00a0\u00bbno-extra-padding\u00a0\u00bb column_padding_position=\u00a0\u00bball\u00a0\u00bb background_color_opacity=\u00a0\u00bb1&Prime; background_hover_color_opacity=\u00a0\u00bb1&Prime; column_link_target=\u00a0\u00bb_self\u00a0\u00bb column_shadow=\u00a0\u00bbnone\u00a0\u00bb column_border_radius=\u00a0\u00bbnone\u00a0\u00bb width=\u00a0\u00bb1\/1&Prime; tablet_width_inherit=\u00a0\u00bbdefault\u00a0\u00bb tablet_text_alignment=\u00a0\u00bbdefault\u00a0\u00bb phone_text_alignment=\u00a0\u00bbdefault\u00a0\u00bb column_border_width=\u00a0\u00bbnone\u00a0\u00bb column_border_style=\u00a0\u00bbsolid\u00a0\u00bb][vc_custom_heading text=\u00a0\u00bb12\u00aa edici\u00f3n ciclo conciertos del Monasterio de Sant Jeroni de Cotalba\u00a0\u00bb font_container=\u00a0\u00bbtag:h3|text_align:left|color:%23ac986d\u00a0\u00bb use_theme_fonts=\u00a0\u00bbyes\u00a0\u00bb][divider line_type=\u00a0\u00bbNo Line\u00a0\u00bb custom_height=\u00a0\u00bb30&Prime;][nectar_btn size=\u00a0\u00bblarge\u00a0\u00bb open_new_tab=\u00a0\u00bbtrue\u00a0\u00bb button_style=\u00a0\u00bbregular\u00a0\u00bb button_color_2=\u00a0\u00bbAccent-Color\u00a0\u00bb icon_family=\u00a0\u00bbnone\u00a0\u00bb url=\u00a0\u00bbhttps:\/\/www.mgticket.com\/cotalba\/\u00a0\u00bb text=\u00a0\u00bbVente de billets\u00a0\u00bb][vc_column_text]Ya est\u00e1 aqu\u00ed la <strong>12\u00aa edici\u00f3n del ciclo de conciertos de 2019 del Monasterio de Sant Jeroni de Cotalba<\/strong> con una programaci\u00f3n muy completa con diversas formaciones de reconocido prestigio. <a href=\"https:\/\/www.mgticket.com\/cotalba\/public\/static\/web\/html\/ES\/MaM_2019.pdf\" target=\"_blank\" rel=\"noopener\">Descargar programa<\/a><\/p>\n<p>Esta 12\u00aa edici\u00f3n, patrocinada por Caixa Popular, comenzar\u00e1 el viernes 12-julio con Ensemble Ars Borgiae y su espectaculo \u00ab\u00a0Lucrecia Borja y Mar\u00eda Enr\u00edquez. Dos duquesas Borja unidas por la m\u00fasica\u00a0\u00bb y finalizar\u00e1 el s\u00e1bado 17-agosto con el recital de Montserrat Mart\u00ed Caball\u00e9 y Luis Santana.<\/p>\n<p>Las entradas de los conciertos se pueden adquirir directamente por internet, combin\u00e1ndolas con visitas guiadas y cenas en el monasterio.<\/p>\n<p><strong>Venta de entradas <\/strong><\/p>\n<ul>\n<li><a href=\"https:\/\/www.mgticket.com\/cotalba\" target=\"_blank\" rel=\"noopener\">Por internet<\/a><\/li>\n<li>En oficinas de <a href=\"https:\/\/www.caixapopular.es\/\" target=\"_blank\" rel=\"noopener\">Caixa Popular<\/a><\/li>\n<\/ul>\n<p>Las entradas de los conciertos se pueden adquirir directamente por internet, combin\u00e1ndolas con visitas guiadas y cenas en el monasterio.[\/vc_column_text][\/vc_column][\/vc_row][vc_row type=\u00a0\u00bbin_container\u00a0\u00bb full_screen_row_position=\u00a0\u00bbmiddle\u00a0\u00bb scene_position=\u00a0\u00bbcenter\u00a0\u00bb text_color=\u00a0\u00bbdark\u00a0\u00bb text_align=\u00a0\u00bbleft\u00a0\u00bb overlay_strength=\u00a0\u00bb0.3&Prime; shape_divider_position=\u00a0\u00bbbottom\u00a0\u00bb][vc_column column_padding=\u00a0\u00bbno-extra-padding\u00a0\u00bb column_padding_position=\u00a0\u00bball\u00a0\u00bb background_color_opacity=\u00a0\u00bb1&Prime; background_hover_color_opacity=\u00a0\u00bb1&Prime; column_link_target=\u00a0\u00bb_self\u00a0\u00bb column_shadow=\u00a0\u00bbnone\u00a0\u00bb column_border_radius=\u00a0\u00bbnone\u00a0\u00bb width=\u00a0\u00bb1\/1&Prime; tablet_width_inherit=\u00a0\u00bbdefault\u00a0\u00bb tablet_text_alignment=\u00a0\u00bbdefault\u00a0\u00bb phone_text_alignment=\u00a0\u00bbdefault\u00a0\u00bb column_border_width=\u00a0\u00bbnone\u00a0\u00bb column_border_style=\u00a0\u00bbsolid\u00a0\u00bb][\/vc_column][\/vc_row]\n","protected":false},"excerpt":{"rendered":"<p>[vc_row type=\u00a0\u00bbin_container\u00a0\u00bb full_screen_row_position=\u00a0\u00bbmiddle\u00a0\u00bb scene_position=\u00a0\u00bbcenter\u00a0\u00bb text_color=\u00a0\u00bbdark\u00a0\u00bb text_align=\u00a0\u00bbleft\u00a0\u00bb overlay_strength=\u00a0\u00bb0.3&Prime; shape_divider_position=\u00a0\u00bbbottom\u00a0\u00bb][vc_column column_padding=\u00a0\u00bbno-extra-padding\u00a0\u00bb column_padding_position=\u00a0\u00bball\u00a0\u00bb background_color_opacity=\u00a0\u00bb1&Prime; background_hover_color_opacity=\u00a0\u00bb1&Prime; column_link_target=\u00a0\u00bb_self\u00a0\u00bb column_shadow=\u00a0\u00bbnone\u00a0\u00bb column_border_radius=\u00a0\u00bbnone\u00a0\u00bb width=\u00a0\u00bb1\/1&Prime; tablet_width_inherit=\u00a0\u00bbdefault\u00a0\u00bb tablet_text_alignment=\u00a0\u00bbdefault\u00a0\u00bb phone_text_alignment=\u00a0\u00bbdefault\u00a0\u00bb column_border_width=\u00a0\u00bbnone\u00a0\u00bb column_border_style=\u00a0\u00bbsolid\u00a0\u00bb][vc_custom_heading text=\u00a0\u00bb12\u00aa edici\u00f3n ciclo conciertos del Monasterio de Sant Jeroni de Cotalba\u00a0\u00bb font_container=\u00a0\u00bbtag:h3|text_align:left|color:%23ac986d\u00a0\u00bb use_theme_fonts=\u00a0\u00bbyes\u00a0\u00bb][divider line_type=\u00a0\u00bbNo Line\u00a0\u00bb custom_height=\u00a0\u00bb30&Prime;][nectar_btn size=\u00a0\u00bblarge\u00a0\u00bb open_new_tab=\u00a0\u00bbtrue\u00a0\u00bb button_style=\u00a0\u00bbregular\u00a0\u00bb button_color_2=\u00a0\u00bbAccent-Color\u00a0\u00bb icon_family=\u00a0\u00bbnone\u00a0\u00bb url=\u00a0\u00bbhttps:\/\/www.mgticket.com\/cotalba\/\u00a0\u00bb text=\u00a0\u00bbVente de billets\u00a0\u00bb][vc_column_text]Ya est\u00e1 aqu\u00ed la 12\u00aa&#8230;<\/p>\n","protected":false},"author":4,"featured_media":9717,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[80,81,44],"tags":[],"class_list":{"0":"post-9724","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-2019-fr","8":"category-conciertos-fr","9":"category-non-classifiee"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>12 \u00e9dition du cycle de concerts du monast\u00e8re de Sant Jeroni de Cotalba<\/title>\n<meta name=\"description\" content=\"12\u00e8me \u00e9dition de la s\u00e9rie de concerts du Monast\u00e8re de Sant Jeroni de Cotalba. Visitez-nous et profitez | Monast\u00e8re de Sant Jeroni de Cotalba.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cotalba.es\/fr\/12a-edicion-ciclo-conciertos-del-monasterio-de-sant-jeroni-de-cotalba\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"12 \u00e9dition du cycle de concerts du monast\u00e8re de Sant Jeroni de Cotalba\" \/>\n<meta property=\"og:description\" content=\"12\u00e8me \u00e9dition de la s\u00e9rie de concerts du Monast\u00e8re de Sant Jeroni de Cotalba. Visitez-nous et profitez | Monast\u00e8re de Sant Jeroni de Cotalba.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cotalba.es\/fr\/12a-edicion-ciclo-conciertos-del-monasterio-de-sant-jeroni-de-cotalba\/\" \/>\n<meta property=\"og:site_name\" content=\"Monasterio de Sant Jeroni de Cotalba\" \/>\n<meta property=\"article:published_time\" content=\"2019-06-13T16:10:22+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-05-27T10:44:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cotalba.es\/wp-content\/uploads\/2019\/06\/cotalba-2019.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1250\" \/>\n\t<meta property=\"og:image:height\" content=\"584\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Monasterio de Sant Jeroni de Cotalba\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Monasterio de Sant Jeroni de Cotalba\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/cotalba.es\\\/fr\\\/12a-edicion-ciclo-conciertos-del-monasterio-de-sant-jeroni-de-cotalba\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cotalba.es\\\/fr\\\/12a-edicion-ciclo-conciertos-del-monasterio-de-sant-jeroni-de-cotalba\\\/\"},\"author\":{\"name\":\"Monasterio de Sant Jeroni de Cotalba\",\"@id\":\"https:\\\/\\\/cotalba.es\\\/#\\\/schema\\\/person\\\/37f57185e182ce7f492746dee3e9f85f\"},\"headline\":\"12\u00aa edici\u00f3n ciclo conciertos del Monasterio de Sant Jeroni de Cotalba\",\"datePublished\":\"2019-06-13T16:10:22+00:00\",\"dateModified\":\"2020-05-27T10:44:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/cotalba.es\\\/fr\\\/12a-edicion-ciclo-conciertos-del-monasterio-de-sant-jeroni-de-cotalba\\\/\"},\"wordCount\":367,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/cotalba.es\\\/fr\\\/12a-edicion-ciclo-conciertos-del-monasterio-de-sant-jeroni-de-cotalba\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cotalba.es\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/cotalba-2019.jpg\",\"articleSection\":[\"2019\",\"Concerts\",\"Non classifi\u00e9(e)\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/cotalba.es\\\/fr\\\/12a-edicion-ciclo-conciertos-del-monasterio-de-sant-jeroni-de-cotalba\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cotalba.es\\\/fr\\\/12a-edicion-ciclo-conciertos-del-monasterio-de-sant-jeroni-de-cotalba\\\/\",\"url\":\"https:\\\/\\\/cotalba.es\\\/fr\\\/12a-edicion-ciclo-conciertos-del-monasterio-de-sant-jeroni-de-cotalba\\\/\",\"name\":\"12 \u00e9dition du cycle de concerts du monast\u00e8re de Sant Jeroni de Cotalba\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cotalba.es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/cotalba.es\\\/fr\\\/12a-edicion-ciclo-conciertos-del-monasterio-de-sant-jeroni-de-cotalba\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/cotalba.es\\\/fr\\\/12a-edicion-ciclo-conciertos-del-monasterio-de-sant-jeroni-de-cotalba\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cotalba.es\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/cotalba-2019.jpg\",\"datePublished\":\"2019-06-13T16:10:22+00:00\",\"dateModified\":\"2020-05-27T10:44:40+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/cotalba.es\\\/#\\\/schema\\\/person\\\/37f57185e182ce7f492746dee3e9f85f\"},\"description\":\"12\u00e8me \u00e9dition de la s\u00e9rie de concerts du Monast\u00e8re de Sant Jeroni de Cotalba. Visitez-nous et profitez | Monast\u00e8re de Sant Jeroni de Cotalba.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cotalba.es\\\/fr\\\/12a-edicion-ciclo-conciertos-del-monasterio-de-sant-jeroni-de-cotalba\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cotalba.es\\\/fr\\\/12a-edicion-ciclo-conciertos-del-monasterio-de-sant-jeroni-de-cotalba\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/cotalba.es\\\/fr\\\/12a-edicion-ciclo-conciertos-del-monasterio-de-sant-jeroni-de-cotalba\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cotalba.es\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/cotalba-2019.jpg\",\"contentUrl\":\"https:\\\/\\\/cotalba.es\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/cotalba-2019.jpg\",\"width\":1250,\"height\":584},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cotalba.es\\\/fr\\\/12a-edicion-ciclo-conciertos-del-monasterio-de-sant-jeroni-de-cotalba\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/cotalba.es\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"12\u00aa edici\u00f3n ciclo conciertos del Monasterio de Sant Jeroni de Cotalba\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cotalba.es\\\/#website\",\"url\":\"https:\\\/\\\/cotalba.es\\\/\",\"name\":\"Monasterio de Sant Jeroni de Cotalba\",\"description\":\"Monasterio de Sant Jeroni de Cotalba\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cotalba.es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/cotalba.es\\\/#\\\/schema\\\/person\\\/37f57185e182ce7f492746dee3e9f85f\",\"name\":\"Monasterio de Sant Jeroni de Cotalba\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/06699b719f834107d86a855f170a92f91ab7eeae415135c3b5a0646031e0d225?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/06699b719f834107d86a855f170a92f91ab7eeae415135c3b5a0646031e0d225?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/06699b719f834107d86a855f170a92f91ab7eeae415135c3b5a0646031e0d225?s=96&d=mm&r=g\",\"caption\":\"Monasterio de Sant Jeroni de Cotalba\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"12 \u00e9dition du cycle de concerts du monast\u00e8re de Sant Jeroni de Cotalba","description":"12\u00e8me \u00e9dition de la s\u00e9rie de concerts du Monast\u00e8re de Sant Jeroni de Cotalba. Visitez-nous et profitez | Monast\u00e8re de Sant Jeroni de Cotalba.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cotalba.es\/fr\/12a-edicion-ciclo-conciertos-del-monasterio-de-sant-jeroni-de-cotalba\/","og_locale":"fr_FR","og_type":"article","og_title":"12 \u00e9dition du cycle de concerts du monast\u00e8re de Sant Jeroni de Cotalba","og_description":"12\u00e8me \u00e9dition de la s\u00e9rie de concerts du Monast\u00e8re de Sant Jeroni de Cotalba. Visitez-nous et profitez | Monast\u00e8re de Sant Jeroni de Cotalba.","og_url":"https:\/\/cotalba.es\/fr\/12a-edicion-ciclo-conciertos-del-monasterio-de-sant-jeroni-de-cotalba\/","og_site_name":"Monasterio de Sant Jeroni de Cotalba","article_published_time":"2019-06-13T16:10:22+00:00","article_modified_time":"2020-05-27T10:44:40+00:00","og_image":[{"width":1250,"height":584,"url":"https:\/\/cotalba.es\/wp-content\/uploads\/2019\/06\/cotalba-2019.jpg","type":"image\/jpeg"}],"author":"Monasterio de Sant Jeroni de Cotalba","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Monasterio de Sant Jeroni de Cotalba","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/cotalba.es\/fr\/12a-edicion-ciclo-conciertos-del-monasterio-de-sant-jeroni-de-cotalba\/#article","isPartOf":{"@id":"https:\/\/cotalba.es\/fr\/12a-edicion-ciclo-conciertos-del-monasterio-de-sant-jeroni-de-cotalba\/"},"author":{"name":"Monasterio de Sant Jeroni de Cotalba","@id":"https:\/\/cotalba.es\/#\/schema\/person\/37f57185e182ce7f492746dee3e9f85f"},"headline":"12\u00aa edici\u00f3n ciclo conciertos del Monasterio de Sant Jeroni de Cotalba","datePublished":"2019-06-13T16:10:22+00:00","dateModified":"2020-05-27T10:44:40+00:00","mainEntityOfPage":{"@id":"https:\/\/cotalba.es\/fr\/12a-edicion-ciclo-conciertos-del-monasterio-de-sant-jeroni-de-cotalba\/"},"wordCount":367,"commentCount":0,"image":{"@id":"https:\/\/cotalba.es\/fr\/12a-edicion-ciclo-conciertos-del-monasterio-de-sant-jeroni-de-cotalba\/#primaryimage"},"thumbnailUrl":"https:\/\/cotalba.es\/wp-content\/uploads\/2019\/06\/cotalba-2019.jpg","articleSection":["2019","Concerts","Non classifi\u00e9(e)"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/cotalba.es\/fr\/12a-edicion-ciclo-conciertos-del-monasterio-de-sant-jeroni-de-cotalba\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/cotalba.es\/fr\/12a-edicion-ciclo-conciertos-del-monasterio-de-sant-jeroni-de-cotalba\/","url":"https:\/\/cotalba.es\/fr\/12a-edicion-ciclo-conciertos-del-monasterio-de-sant-jeroni-de-cotalba\/","name":"12 \u00e9dition du cycle de concerts du monast\u00e8re de Sant Jeroni de Cotalba","isPartOf":{"@id":"https:\/\/cotalba.es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cotalba.es\/fr\/12a-edicion-ciclo-conciertos-del-monasterio-de-sant-jeroni-de-cotalba\/#primaryimage"},"image":{"@id":"https:\/\/cotalba.es\/fr\/12a-edicion-ciclo-conciertos-del-monasterio-de-sant-jeroni-de-cotalba\/#primaryimage"},"thumbnailUrl":"https:\/\/cotalba.es\/wp-content\/uploads\/2019\/06\/cotalba-2019.jpg","datePublished":"2019-06-13T16:10:22+00:00","dateModified":"2020-05-27T10:44:40+00:00","author":{"@id":"https:\/\/cotalba.es\/#\/schema\/person\/37f57185e182ce7f492746dee3e9f85f"},"description":"12\u00e8me \u00e9dition de la s\u00e9rie de concerts du Monast\u00e8re de Sant Jeroni de Cotalba. Visitez-nous et profitez | Monast\u00e8re de Sant Jeroni de Cotalba.","breadcrumb":{"@id":"https:\/\/cotalba.es\/fr\/12a-edicion-ciclo-conciertos-del-monasterio-de-sant-jeroni-de-cotalba\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cotalba.es\/fr\/12a-edicion-ciclo-conciertos-del-monasterio-de-sant-jeroni-de-cotalba\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/cotalba.es\/fr\/12a-edicion-ciclo-conciertos-del-monasterio-de-sant-jeroni-de-cotalba\/#primaryimage","url":"https:\/\/cotalba.es\/wp-content\/uploads\/2019\/06\/cotalba-2019.jpg","contentUrl":"https:\/\/cotalba.es\/wp-content\/uploads\/2019\/06\/cotalba-2019.jpg","width":1250,"height":584},{"@type":"BreadcrumbList","@id":"https:\/\/cotalba.es\/fr\/12a-edicion-ciclo-conciertos-del-monasterio-de-sant-jeroni-de-cotalba\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/cotalba.es\/fr\/"},{"@type":"ListItem","position":2,"name":"12\u00aa edici\u00f3n ciclo conciertos del Monasterio de Sant Jeroni de Cotalba"}]},{"@type":"WebSite","@id":"https:\/\/cotalba.es\/#website","url":"https:\/\/cotalba.es\/","name":"Monasterio de Sant Jeroni de Cotalba","description":"Monasterio de Sant Jeroni de Cotalba","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cotalba.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/cotalba.es\/#\/schema\/person\/37f57185e182ce7f492746dee3e9f85f","name":"Monasterio de Sant Jeroni de Cotalba","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/06699b719f834107d86a855f170a92f91ab7eeae415135c3b5a0646031e0d225?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/06699b719f834107d86a855f170a92f91ab7eeae415135c3b5a0646031e0d225?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/06699b719f834107d86a855f170a92f91ab7eeae415135c3b5a0646031e0d225?s=96&d=mm&r=g","caption":"Monasterio de Sant Jeroni de Cotalba"}}]}},"_links":{"self":[{"href":"https:\/\/cotalba.es\/fr\/wp-json\/wp\/v2\/posts\/9724","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cotalba.es\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cotalba.es\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cotalba.es\/fr\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/cotalba.es\/fr\/wp-json\/wp\/v2\/comments?post=9724"}],"version-history":[{"count":5,"href":"https:\/\/cotalba.es\/fr\/wp-json\/wp\/v2\/posts\/9724\/revisions"}],"predecessor-version":[{"id":10381,"href":"https:\/\/cotalba.es\/fr\/wp-json\/wp\/v2\/posts\/9724\/revisions\/10381"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cotalba.es\/fr\/wp-json\/wp\/v2\/media\/9717"}],"wp:attachment":[{"href":"https:\/\/cotalba.es\/fr\/wp-json\/wp\/v2\/media?parent=9724"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cotalba.es\/fr\/wp-json\/wp\/v2\/categories?post=9724"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cotalba.es\/fr\/wp-json\/wp\/v2\/tags?post=9724"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}