{"id":9866,"date":"2019-05-31T11:47:14","date_gmt":"2019-05-31T11:47:14","guid":{"rendered":"https:\/\/cotalba.es\/art\/custodia\/"},"modified":"2021-09-21T21:33:34","modified_gmt":"2021-09-21T21:33:34","slug":"custodia","status":"publish","type":"page","link":"https:\/\/cotalba.es\/val\/art\/custodia\/","title":{"rendered":"Custodia"},"content":{"rendered":"[vc_row type=&#8221;full_width_content&#8221; full_screen_row_position=&#8221;middle&#8221; bg_image=&#8221;8428&#8243; bg_position=&#8221;center center&#8221; bg_repeat=&#8221;no-repeat&#8221; parallax_bg=&#8221;true&#8221; parallax_bg_speed=&#8221;medium&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; top_padding=&#8221;200&#8243; bottom_padding=&#8221;200&#8243; overlay_strength=&#8221;0.3&#8243; shape_divider_position=&#8221;bottom&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;padding-10-percent&#8221; column_padding_position=&#8221;left-right&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_link_target=&#8221;_self&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_row_inner equal_height=&#8221;yes&#8221; content_placement=&#8221;middle&#8221; column_margin=&#8221;default&#8221; text_align=&#8221;left&#8221;][vc_column_inner column_padding=&#8221;padding-5-percent&#8221; column_padding_position=&#8221;all&#8221; background_color=&#8221;#1d0e00&#8243; background_color_opacity=&#8221;0.6&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; width=&#8221;2\/3&#8243; tablet_width_inherit=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_custom_heading text=&#8221;Custodia&#8221; font_container=&#8221;tag:h1|text_align:left|color:%23ffffff&#8221; use_theme_fonts=&#8221;yes&#8221;][vc_custom_heading text=&#8221;Realitzada per Fra Antonio Sancho de Benevento en 1548, fou un dels millors exemples d&#8217;orfebrer\u00eda renaixentista espanyola.&#8221; font_container=&#8221;tag:h4|text_align:left|color:%23ffffff&#8221; use_theme_fonts=&#8221;yes&#8221;][\/vc_column_inner][vc_column_inner column_padding=&#8221;padding-5-percent&#8221; column_padding_position=&#8221;left-right&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; width=&#8221;1\/3&#8243; tablet_width_inherit=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_content&#8221; full_screen_row_position=&#8221;middle&#8221; equal_height=&#8221;yes&#8221; content_placement=&#8221;middle&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; top_padding=&#8221;60&#8243; overlay_strength=&#8221;0.3&#8243; shape_divider_position=&#8221;bottom&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;padding-5-percent&#8221; column_padding_position=&#8221;left-right&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_link_target=&#8221;_self&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; bottom_margin=&#8221;60&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_row_inner equal_height=&#8221;yes&#8221; content_placement=&#8221;middle&#8221; column_margin=&#8221;default&#8221; text_align=&#8221;left&#8221;][vc_column_inner column_padding=&#8221;padding-5-percent&#8221; column_padding_position=&#8221;left-right&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][nectar_btn size=&#8221;large&#8221; open_new_tab=&#8221;true&#8221; button_style=&#8221;regular&#8221; button_color_2=&#8221;Accent-Color&#8221; icon_family=&#8221;none&#8221; url=&#8221;https:\/\/www.mgticket.com\/cotalba\/public\/janto\/&#8221; text=&#8221;Comprar entrada&#8221; margin_bottom=&#8221;30&#8243;][vc_column_text]Una obra d\u2019orfebreria destacable dins del conjunt mon\u00e0stic era la cust\u00f2dia, realitzada per Fra Antonio Sancho de Benevento en 1548, frare i orfebre del monasteri.<\/p>\n<p>Es tractava d\u2019una pe\u00e7a en forma de torre de quatre cossos realitzada en bronze sobredaurat, i que media un metre d\u2019altura. En ella es desenrotllava un ric programa iconogr\u00e0fic representat amb minuci\u00f3s detall.<\/p>\n<p>La seua qualitat estil\u00edstica i t\u00e8cnica va ser comparable a les cust\u00f2dies de les catedrals de Toledo o de Santiago de Compostela, sent un dels millors exemples d\u2019orfebreria renaixentista espanyola.<\/p>\n<p>Desapareguda despr\u00e9s de la guerra civil espanyola, nom\u00e9s es conserva d\u2019ella l\u2019ostensori.[\/vc_column_text][\/vc_column_inner][vc_column_inner column_padding=&#8221;padding-5-percent&#8221; column_padding_position=&#8221;left-right&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; top_margin=&#8221;-150&#8243; column_link_target=&#8221;_self&#8221; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][image_with_animation image_url=&#8221;7631&#8243; alignment=&#8221;&#8221; animation=&#8221;Fade In&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; max_width=&#8221;100%&#8221;][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_content&#8221; full_screen_row_position=&#8221;middle&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; top_padding=&#8221;60&#8243; overlay_strength=&#8221;0.3&#8243; shape_divider_position=&#8221;bottom&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;padding-5-percent&#8221; column_padding_position=&#8221;left-right&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_link_target=&#8221;_self&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; bottom_margin=&#8221;60&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_gallery type=&#8221;flickity_style&#8221; images=&#8221;8429,8430,8431&#8243; flickity_controls=&#8221;pagination&#8221; flickity_desktop_columns=&#8221;1&#8243; flickity_small_desktop_columns=&#8221;1&#8243; flickity_tablet_columns=&#8221;1&#8243; flickity_free_scroll=&#8221;true&#8221; flickity_box_shadow=&#8221;none&#8221; onclick=&#8221;link_image&#8221; img_size=&#8221;600&#215;400&#8243;][\/vc_column][\/vc_row]\n","protected":false},"excerpt":{"rendered":"<p>[vc_row type=&#8221;full_width_content&#8221; full_screen_row_position=&#8221;middle&#8221; bg_image=&#8221;8428&#8243; bg_position=&#8221;center center&#8221; bg_repeat=&#8221;no-repeat&#8221; parallax_bg=&#8221;true&#8221; parallax_bg_speed=&#8221;medium&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; top_padding=&#8221;200&#8243; bottom_padding=&#8221;200&#8243; overlay_strength=&#8221;0.3&#8243; shape_divider_position=&#8221;bottom&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;padding-10-percent&#8221; column_padding_position=&#8221;left-right&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_link_target=&#8221;_self&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_row_inner equal_height=&#8221;yes&#8221; content_placement=&#8221;middle&#8221; column_margin=&#8221;default&#8221; text_align=&#8221;left&#8221;][vc_column_inner column_padding=&#8221;padding-5-percent&#8221; column_padding_position=&#8221;all&#8221; background_color=&#8221;#1d0e00&#8243; background_color_opacity=&#8221;0.6&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; width=&#8221;2\/3&#8243; tablet_width_inherit=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_custom_heading text=&#8221;Custodia&#8221; font_container=&#8221;tag:h1|text_align:left|color:%23ffffff&#8221; use_theme_fonts=&#8221;yes&#8221;][vc_custom_heading text=&#8221;Realitzada&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":9865,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-9866","page","type-page","status-publish"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Custodia | Monasteri de Sant Jeroni de Cotalba<\/title>\n<meta name=\"description\" content=\"Custodia | Monasteri de Sant Jeroni de Cotalba\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cotalba.es\/val\/art\/custodia\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Custodia | Monasteri de Sant Jeroni de Cotalba\" \/>\n<meta property=\"og:description\" content=\"Custodia | Monasteri de Sant Jeroni de Cotalba\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cotalba.es\/val\/art\/custodia\/\" \/>\n<meta property=\"og:site_name\" content=\"Monasterio de Sant Jeroni de Cotalba\" \/>\n<meta property=\"article:modified_time\" content=\"2021-09-21T21:33:34+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cotalba.es\\\/val\\\/art\\\/custodia\\\/\",\"url\":\"https:\\\/\\\/cotalba.es\\\/val\\\/art\\\/custodia\\\/\",\"name\":\"Custodia | Monasteri de Sant Jeroni de Cotalba\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cotalba.es\\\/#website\"},\"datePublished\":\"2019-05-31T11:47:14+00:00\",\"dateModified\":\"2021-09-21T21:33:34+00:00\",\"description\":\"Custodia | Monasteri de Sant Jeroni de Cotalba\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cotalba.es\\\/val\\\/art\\\/custodia\\\/#breadcrumb\"},\"inLanguage\":\"val\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cotalba.es\\\/val\\\/art\\\/custodia\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cotalba.es\\\/val\\\/art\\\/custodia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/cotalba.es\\\/val\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Art\",\"item\":\"https:\\\/\\\/cotalba.es\\\/val\\\/art\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Custodia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cotalba.es\\\/#website\",\"url\":\"https:\\\/\\\/cotalba.es\\\/\",\"name\":\"Monasterio de Sant Jeroni de Cotalba\",\"description\":\"Monasterio de Sant Jeroni de Cotalba\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cotalba.es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"val\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Custodia | Monasteri de Sant Jeroni de Cotalba","description":"Custodia | Monasteri de Sant Jeroni de Cotalba","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cotalba.es\/val\/art\/custodia\/","og_locale":"en_US","og_type":"article","og_title":"Custodia | Monasteri de Sant Jeroni de Cotalba","og_description":"Custodia | Monasteri de Sant Jeroni de Cotalba","og_url":"https:\/\/cotalba.es\/val\/art\/custodia\/","og_site_name":"Monasterio de Sant Jeroni de Cotalba","article_modified_time":"2021-09-21T21:33:34+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/cotalba.es\/val\/art\/custodia\/","url":"https:\/\/cotalba.es\/val\/art\/custodia\/","name":"Custodia | Monasteri de Sant Jeroni de Cotalba","isPartOf":{"@id":"https:\/\/cotalba.es\/#website"},"datePublished":"2019-05-31T11:47:14+00:00","dateModified":"2021-09-21T21:33:34+00:00","description":"Custodia | Monasteri de Sant Jeroni de Cotalba","breadcrumb":{"@id":"https:\/\/cotalba.es\/val\/art\/custodia\/#breadcrumb"},"inLanguage":"val","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cotalba.es\/val\/art\/custodia\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/cotalba.es\/val\/art\/custodia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/cotalba.es\/val\/"},{"@type":"ListItem","position":2,"name":"Art","item":"https:\/\/cotalba.es\/val\/art\/"},{"@type":"ListItem","position":3,"name":"Custodia"}]},{"@type":"WebSite","@id":"https:\/\/cotalba.es\/#website","url":"https:\/\/cotalba.es\/","name":"Monasterio de Sant Jeroni de Cotalba","description":"Monasterio de Sant Jeroni de Cotalba","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cotalba.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"val"}]}},"_links":{"self":[{"href":"https:\/\/cotalba.es\/val\/wp-json\/wp\/v2\/pages\/9866","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cotalba.es\/val\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/cotalba.es\/val\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/cotalba.es\/val\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/cotalba.es\/val\/wp-json\/wp\/v2\/comments?post=9866"}],"version-history":[{"count":11,"href":"https:\/\/cotalba.es\/val\/wp-json\/wp\/v2\/pages\/9866\/revisions"}],"predecessor-version":[{"id":12718,"href":"https:\/\/cotalba.es\/val\/wp-json\/wp\/v2\/pages\/9866\/revisions\/12718"}],"up":[{"embeddable":true,"href":"https:\/\/cotalba.es\/val\/wp-json\/wp\/v2\/pages\/9865"}],"wp:attachment":[{"href":"https:\/\/cotalba.es\/val\/wp-json\/wp\/v2\/media?parent=9866"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}