{"id":9876,"date":"2019-05-29T19:25:07","date_gmt":"2019-05-29T19:25:07","guid":{"rendered":"https:\/\/cotalba.es\/bibliografia\/"},"modified":"2019-06-16T15:50:45","modified_gmt":"2019-06-16T15:50:45","slug":"bibliografia","status":"publish","type":"page","link":"https:\/\/cotalba.es\/val\/bibliografia\/","title":{"rendered":"Bibliografia"},"content":{"rendered":"[vc_row type=&#8221;full_width_content&#8221; full_screen_row_position=&#8221;middle&#8221; bg_image=&#8221;8350&#8243; bg_position=&#8221;center center&#8221; bg_repeat=&#8221;no-repeat&#8221; parallax_bg=&#8221;true&#8221; parallax_bg_speed=&#8221;medium&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; top_padding=&#8221;200&#8243; bottom_padding=&#8221;200&#8243; overlay_strength=&#8221;0.3&#8243; shape_divider_position=&#8221;bottom&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;padding-10-percent&#8221; column_padding_position=&#8221;left-right&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_link_target=&#8221;_self&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_row_inner equal_height=&#8221;yes&#8221; content_placement=&#8221;middle&#8221; column_margin=&#8221;default&#8221; text_align=&#8221;left&#8221;][vc_column_inner column_padding=&#8221;padding-5-percent&#8221; column_padding_position=&#8221;all&#8221; background_color=&#8221;#1d0e00&#8243; background_color_opacity=&#8221;0.6&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; width=&#8221;2\/3&#8243; tablet_width_inherit=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_custom_heading text=&#8221;Bibliografia&#8221; font_container=&#8221;tag:h1|text_align:left|color:%23ffffff&#8221; use_theme_fonts=&#8221;yes&#8221;][vc_custom_heading text=&#8221;Llibres i publicacions sobre el monasteri i el seu entorn, relacionats amb la seua hist\u00f2ria o amb els personatges hist\u00f2rics que passaren per ell.&#8221; font_container=&#8221;tag:h4|text_align:left|color:%23ffffff&#8221; use_theme_fonts=&#8221;yes&#8221;][nectar_btn size=&#8221;large&#8221; open_new_tab=&#8221;true&#8221; button_style=&#8221;regular&#8221; button_color_2=&#8221;Accent-Color&#8221; icon_family=&#8221;none&#8221; url=&#8221;https:\/\/www.mgticket.com\/cotalba\/public\/janto\/&#8221; text=&#8221;Comprar entrada&#8221; margin_top=&#8221;20&#8243;][\/vc_column_inner][vc_column_inner column_padding=&#8221;padding-5-percent&#8221; column_padding_position=&#8221;left-right&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; width=&#8221;1\/3&#8243; tablet_width_inherit=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; equal_height=&#8221;yes&#8221; content_placement=&#8221;middle&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; top_padding=&#8221;60&#8243; bottom_padding=&#8221;30&#8243; overlay_strength=&#8221;0.3&#8243; shape_divider_position=&#8221;bottom&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_position=&#8221;left-right&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_link_target=&#8221;_self&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; width=&#8221;1\/4&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][image_with_animation image_url=&#8221;7328&#8243; alignment=&#8221;&#8221; animation=&#8221;None&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;small_depth&#8221; max_width=&#8221;100%&#8221;][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_position=&#8221;left-right&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_link_target=&#8221;_self&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_column_text]\n<h5 class=\"title style-scope ytd-video-primary-info-renderer\">\u00a0&#8220;Real Monasterio de San Jer\u00f3nimo de Cotalba&#8221;<\/h5>\n[\/vc_column_text][divider line_type=&#8221;No Line&#8221; custom_height=&#8221;10&#8243;][vc_column_text]<strong>Autors:<\/strong> Fernando Mut Oltra i Vicente Palmer Terrades.<br \/>\n<strong>\u2028Editor:<\/strong>\u00a0Fernando Mut (Gandia).<br \/>\n<strong>\u2028Any<\/strong>:\u00a01999.<br \/>\n<strong>\u2028Idioma:<\/strong> Castell\u00e0<br \/>\n<strong>\u2028ISBN:<\/strong>\u00a084-60591166<br \/>\n<strong>\u2028P\u00e0gines:<\/strong>\u00a0254 p\u00e0gines.[\/vc_column_text][toggles style=&#8221;minimal&#8221;][toggle color=&#8221;Accent-Color&#8221; title=&#8221;Contingut&#8221;][vc_column_text]Introducci\u00f3, Sant Jeroni, L&#8217;ordre, El monestir, L&#8217;art, Relaci\u00f3 amb altres monasteris, Cronologia, Recintes de l&#8217;entorn, L&#8217;entorn, Lectura de l&#8217;edifici, Desamortitzaci\u00f3, Exclaustraci\u00f3, L&#8217;ad\u00e9u, Annexos, Arxius del Regne de Valencia, Arxiu Hist\u00f2ric Nacional, Declaraci\u00f3 edifici hist\u00f2ric, Bibliografia i Cartografia.[\/vc_column_text][\/toggle][\/toggles][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_position=&#8221;all&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_link_target=&#8221;_self&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; width=&#8221;1\/4&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; equal_height=&#8221;yes&#8221; content_placement=&#8221;middle&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; top_padding=&#8221;60&#8243; bottom_padding=&#8221;60&#8243; overlay_strength=&#8221;0.3&#8243; shape_divider_position=&#8221;bottom&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_position=&#8221;left-right&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_link_target=&#8221;_self&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; width=&#8221;1\/4&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][image_with_animation image_url=&#8221;7334&#8243; alignment=&#8221;&#8221; animation=&#8221;None&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;small_depth&#8221; max_width=&#8221;100%&#8221;][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_position=&#8221;left-right&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_link_target=&#8221;_self&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_column_text]\n<h5 class=\"title style-scope ytd-video-primary-info-renderer\">&#8220;Sant Jeroni de Cotalba: desintegraci\u00f3 feudal i vida mon\u00e0stica (segles XVIII i XIX)&#8221;.<\/h5>\n[\/vc_column_text][divider line_type=&#8221;No Line&#8221; custom_height=&#8221;10&#8243;][vc_column_text]<strong>Autor:<\/strong>\u00a0Jes\u00fas Eduard Alonso i L\u00f3pez.<br \/>\n<strong>Editorial:<\/strong>\u00a0CEIC Alfons el Vell (Gandia)<br \/>\n<strong>Any:<\/strong>\u00a01988.<br \/>\n<strong>Idioma:<\/strong> Valenci\u00e0<br \/>\n<strong>\u2028ISBN:<\/strong>\u00a084-86927-00-5<br \/>\n<strong>P\u00e0gines:<\/strong>\u00a0221 p\u00e0gines.[\/vc_column_text][toggles style=&#8221;minimal&#8221;][toggle color=&#8221;Accent-Color&#8221; title=&#8221;Sinopsis&#8221;][vc_column_text]\n<p class=\"p1\">&#8220;El present estudi no \u00e9s un treball m\u00e9s sobre una instituci\u00f3 significativa per a la historia d&#8217;un \u00e0mbit local redu\u00eft. En estudiar una realitat limitada, hi ha el prop\u00f2sit de fer una aproximaci\u00f3 ampla a l&#8217;an\u00e0lisi del canvi social que don\u00e0 origen al mon contemporani. Conscient de que el canvi social no es pot identificar \u00fanicament amb el canvi econ\u00f2mic, l&#8217;autor ha procurat interrogar-se sobre la mentalitat i els criteris que, a partir d&#8217;una instituci\u00f3 religiosa, acabaren influint en la vida i el treball dels h\u00f2mens. Al final, el conjunt de la vida d&#8217;un espai, centrat principalment entre la Safor i la Vall d&#8217;Albaida, girava al voltant dels frares de Sant Jeroni de Cotalba.&#8221; Pr\u00f2leg de Jes\u00fas Mill\u00e1n.<\/p>\n[\/vc_column_text][\/toggle][\/toggles][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_position=&#8221;all&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_link_target=&#8221;_self&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; width=&#8221;1\/4&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; equal_height=&#8221;yes&#8221; content_placement=&#8221;middle&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; top_padding=&#8221;60&#8243; bottom_padding=&#8221;60&#8243; overlay_strength=&#8221;0.3&#8243; shape_divider_position=&#8221;bottom&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_position=&#8221;left-right&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_link_target=&#8221;_self&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; width=&#8221;1\/4&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][image_with_animation image_url=&#8221;7352&#8243; alignment=&#8221;&#8221; animation=&#8221;None&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;small_depth&#8221; max_width=&#8221;100%&#8221;][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_position=&#8221;left-right&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_link_target=&#8221;_self&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_column_text]\n<h5 class=\"title style-scope ytd-video-primary-info-renderer\">\u00a0El Monasterio de San Jer\u00f3nimo de Cotalba de Gandia<\/h5>\n[\/vc_column_text][divider line_type=&#8221;No Line&#8221; custom_height=&#8221;10&#8243;][vc_column_text]<strong>Autor:<\/strong>\u00a0Felipe G. Perles Mart\u00ed<br \/>\n<strong>Editorial<\/strong><strong>:\u00a0<\/strong>Revista Vall de Bair\u00e9n, Gandia<br \/>\n<strong>Idioma:<\/strong> Castell\u00e0<br \/>\n<strong>Any:\u00a0<\/strong>1988-89<br \/>\n<strong>P\u00e0gines:<\/strong>\u00a0104 p\u00e0gines.[\/vc_column_text][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_position=&#8221;all&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_link_target=&#8221;_self&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; width=&#8221;1\/4&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; equal_height=&#8221;yes&#8221; content_placement=&#8221;middle&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; top_padding=&#8221;60&#8243; bottom_padding=&#8221;60&#8243; overlay_strength=&#8221;0.3&#8243; shape_divider_position=&#8221;bottom&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_position=&#8221;left-right&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_link_target=&#8221;_self&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; width=&#8221;1\/4&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][image_with_animation image_url=&#8221;7354&#8243; alignment=&#8221;&#8221; animation=&#8221;None&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;small_depth&#8221; max_width=&#8221;100%&#8221;][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_position=&#8221;left-right&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_link_target=&#8221;_self&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_column_text]\n<h5 class=\"title style-scope ytd-video-primary-info-renderer\">La Baronia de Palma i la casa Tols\u00e0-Moncada<\/h5>\n[\/vc_column_text][divider line_type=&#8221;No Line&#8221; custom_height=&#8221;10&#8243;][vc_column_text]<strong>Autor:<\/strong>\u00a0Maite Framis Montoliu<br \/>\n<strong>Editorial:<\/strong>\u00a0La Xara Edicions, Simat de la Valldigna.<br \/>\n<strong>Any:<\/strong>\u00a02002<br \/>\n<strong>Idioma:<\/strong> Valenci\u00e0<br \/>\n<strong>P\u00e0gines:<\/strong>\u00a0130 p\u00e0gines[\/vc_column_text][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_position=&#8221;all&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_link_target=&#8221;_self&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; width=&#8221;1\/4&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; equal_height=&#8221;yes&#8221; content_placement=&#8221;middle&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; top_padding=&#8221;60&#8243; bottom_padding=&#8221;60&#8243; overlay_strength=&#8221;0.3&#8243; shape_divider_position=&#8221;bottom&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_position=&#8221;left-right&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_link_target=&#8221;_self&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; width=&#8221;1\/4&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][image_with_animation image_url=&#8221;7355&#8243; alignment=&#8221;&#8221; animation=&#8221;None&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;small_depth&#8221; max_width=&#8221;100%&#8221;][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_position=&#8221;left-right&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_link_target=&#8221;_self&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_column_text]\n<h5 class=\"title style-scope ytd-video-primary-info-renderer\">Entre senyors, frares i bandolers. Noticia de l\u2019antic terme general del castell de Palma en el S XVII<\/h5>\n[\/vc_column_text][divider line_type=&#8221;No Line&#8221; custom_height=&#8221;10&#8243;][vc_column_text]<strong>Autor:<\/strong>\u00a0Vicent Mahiques Roig<br \/>\n<strong>Editorial:<\/strong>\u00a0CEIC Alfons el Vell, Gandia.<br \/>\n<strong>Any:<\/strong>\u00a02006<br \/>\n<strong>Idioma:<\/strong> Valenci\u00e0<br \/>\n<strong>ISBN:<\/strong>\u00a084-86927-92-7<br \/>\n<strong>P\u00e0gines:<\/strong>\u00a0343 p\u00e0gines[\/vc_column_text][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_position=&#8221;all&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_link_target=&#8221;_self&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; width=&#8221;1\/4&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; equal_height=&#8221;yes&#8221; content_placement=&#8221;middle&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; top_padding=&#8221;60&#8243; bottom_padding=&#8221;60&#8243; overlay_strength=&#8221;0.3&#8243; shape_divider_position=&#8221;bottom&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_position=&#8221;left-right&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_link_target=&#8221;_self&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; width=&#8221;1\/4&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][image_with_animation image_url=&#8221;7357&#8243; alignment=&#8221;&#8221; animation=&#8221;None&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;small_depth&#8221; max_width=&#8221;100%&#8221;][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_position=&#8221;left-right&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_link_target=&#8221;_self&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_column_text]\n<h5 class=\"title style-scope ytd-video-primary-info-renderer\">Nicol\u00e1s Borr\u00e1s Falc\u00f3<\/h5>\n[\/vc_column_text][divider line_type=&#8221;No Line&#8221; custom_height=&#8221;10&#8243;][vc_column_text]<strong>Autor:<\/strong>\u00a0Varis, Ajuntament de Cocentaina.<br \/>\n<strong>Editorial:<\/strong>\u00a0Ajuntament de Cocentaina (Alacant).<br \/>\n<strong>Any:\u00a0<\/strong>2010<br \/>\n<strong>Idioma:<\/strong>\u00a0 Castell\u00e0<br \/>\n<strong>P\u00e0gines:<\/strong>\u00a0187 p\u00e0gines[\/vc_column_text][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_position=&#8221;all&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_link_target=&#8221;_self&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; width=&#8221;1\/4&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; equal_height=&#8221;yes&#8221; content_placement=&#8221;middle&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; top_padding=&#8221;60&#8243; bottom_padding=&#8221;60&#8243; overlay_strength=&#8221;0.3&#8243; shape_divider_position=&#8221;bottom&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_position=&#8221;left-right&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_link_target=&#8221;_self&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; width=&#8221;1\/4&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][image_with_animation image_url=&#8221;7358&#8243; alignment=&#8221;&#8221; animation=&#8221;None&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;small_depth&#8221; max_width=&#8221;100%&#8221;][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_position=&#8221;left-right&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_link_target=&#8221;_self&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; width=&#8221;3\/4&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_column_text]\n<h5 class=\"title style-scope ytd-video-primary-info-renderer\">El arte de la Orden Jer\u00f3nima: historia y mecenazgo<\/h5>\n[\/vc_column_text][divider line_type=&#8221;No Line&#8221; custom_height=&#8221;10&#8243;][vc_column_text]<strong>Autors:<\/strong>\u00a0Isabel Mateo G\u00f3mez, Amelia L\u00f3pez-Yarto,\u00a0 Jos\u00e9 Mar\u00eda Prados Garc\u00eda.<br \/>\n<strong>Editorial:\u00a0<\/strong>Encuentro<br \/>\n<strong>Any:<\/strong>\u00a01999<br \/>\n<strong>Idioma:<\/strong> Castell\u00e0<br \/>\n<strong>ISBN:<\/strong>\u00a08474905524<br \/>\n<strong>P\u00e0gines:<\/strong>\u00a0335 p\u00e0gines<br \/>\n<a href=\"https:\/\/books.google.es\/books?id=uPOzwWCir-0C&amp;printsec=frontcover&amp;hl=es&amp;source=gbs_ge_summary_r&amp;cad=0#v=onepage&amp;q&amp;f=false\" target=\"_blank\" rel=\"noopener\">Llibre online<\/a>[\/vc_column_text][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; equal_height=&#8221;yes&#8221; content_placement=&#8221;middle&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; top_padding=&#8221;60&#8243; bottom_padding=&#8221;60&#8243; overlay_strength=&#8221;0.3&#8243; shape_divider_position=&#8221;bottom&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_position=&#8221;left-right&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_link_target=&#8221;_self&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; width=&#8221;1\/4&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][image_with_animation image_url=&#8221;7359&#8243; alignment=&#8221;&#8221; animation=&#8221;None&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;small_depth&#8221; max_width=&#8221;100%&#8221;][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_position=&#8221;left-right&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_link_target=&#8221;_self&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; width=&#8221;3\/4&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_column_text]\n<h5 class=\"title style-scope ytd-video-primary-info-renderer\">Monasterios Valencianos: su historia y su arte<\/h5>\n[\/vc_column_text][divider line_type=&#8221;No Line&#8221; custom_height=&#8221;10&#8243;][vc_column_text]<strong>Autor:<\/strong>\u00a0Carlos Sarthou Carreres<br \/>\n<strong>Editorial:<\/strong>\u00a0La Semana Gr\u00e1fica<br \/>\n<strong>Any:<\/strong>\u00a01943<br \/>\n<strong>Idioma:<\/strong> Castell\u00e0<br \/>\n<strong>P\u00e0gines:<\/strong>\u00a0333 p\u00e0gines[\/vc_column_text][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; equal_height=&#8221;yes&#8221; content_placement=&#8221;middle&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; top_padding=&#8221;60&#8243; bottom_padding=&#8221;60&#8243; overlay_strength=&#8221;0.3&#8243; shape_divider_position=&#8221;bottom&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_position=&#8221;left-right&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_link_target=&#8221;_self&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; width=&#8221;1\/4&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][image_with_animation image_url=&#8221;7359&#8243; alignment=&#8221;&#8221; animation=&#8221;None&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;small_depth&#8221; max_width=&#8221;100%&#8221;][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_position=&#8221;left-right&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_link_target=&#8221;_self&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; width=&#8221;3\/4&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_column_text]\n<h5 class=\"title style-scope ytd-video-primary-info-renderer\">\u00a0Los monasterios valencianos<\/h5>\n[\/vc_column_text][divider line_type=&#8221;No Line&#8221; custom_height=&#8221;10&#8243;][vc_column_text]<strong>Autor:<\/strong>\u00a0Mar\u00eda Desamparados Cabanes Pecourt<br \/>\n<strong>Editorial:<\/strong>\u00a0Universitat de Valencia. Facultat de Filosof\u00eda i Lletres, Departament de Hist\u00f2ria Medieval.<br \/>\n<strong>Any:<\/strong>\u00a01974<br \/>\n<strong>Idioma:<\/strong> Castell\u00e0<br \/>\n<strong>ISBN:<\/strong>\u00a08460060365<br \/>\n<strong>P\u00e0gines:<\/strong>\u00a0329 p\u00e0gines[\/vc_column_text][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; equal_height=&#8221;yes&#8221; content_placement=&#8221;middle&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; top_padding=&#8221;60&#8243; bottom_padding=&#8221;60&#8243; overlay_strength=&#8221;0.3&#8243; shape_divider_position=&#8221;bottom&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_position=&#8221;left-right&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_link_target=&#8221;_self&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; width=&#8221;1\/4&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][image_with_animation image_url=&#8221;7361&#8243; alignment=&#8221;&#8221; animation=&#8221;None&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;small_depth&#8221; max_width=&#8221;100%&#8221;][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_position=&#8221;left-right&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_link_target=&#8221;_self&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; width=&#8221;3\/4&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_column_text]\n<h5 class=\"title style-scope ytd-video-primary-info-renderer\">Monasterios valencianos<\/h5>\n[\/vc_column_text][divider line_type=&#8221;No Line&#8221; custom_height=&#8221;10&#8243;][vc_column_text]<strong>Autor:<\/strong>\u00a0Bernat Montagud Piera<br \/>\n<strong>Editorial:<\/strong>\u00a0Generalitat Valenciana, Conselleria de Cultura, Educaci\u00f3 i Ci\u00e8ncia.<br \/>\n<strong>Colecci\u00f3n:<\/strong>\u00a0Rutes d&#8217;aproximaci\u00f3 al patrimoni cultural valenci\u00e0, Volumen n\u00ba 3.<br \/>\n<strong>Any:\u00a0<\/strong>1984<br \/>\n<strong>Idioma:<\/strong> Castell\u00e0<br \/>\n<strong>ISBN:<\/strong>\u00a08475790224<br \/>\n<strong>P\u00e0gines:<\/strong>\u00a052 p\u00e0gines.[\/vc_column_text][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; equal_height=&#8221;yes&#8221; content_placement=&#8221;middle&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; top_padding=&#8221;60&#8243; bottom_padding=&#8221;60&#8243; overlay_strength=&#8221;0.3&#8243; shape_divider_position=&#8221;bottom&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_position=&#8221;left-right&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_link_target=&#8221;_self&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; width=&#8221;1\/4&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][image_with_animation image_url=&#8221;7362&#8243; alignment=&#8221;&#8221; animation=&#8221;None&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;small_depth&#8221; max_width=&#8221;100%&#8221;][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_position=&#8221;left-right&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_link_target=&#8221;_self&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; width=&#8221;3\/4&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_column_text]\n<h5 class=\"title style-scope ytd-video-primary-info-renderer\">Els Borja, valencians.<\/h5>\n[\/vc_column_text][divider line_type=&#8221;No Line&#8221; custom_height=&#8221;10&#8243;][vc_column_text]<strong>Autor:<\/strong>\u00a0Antoni Atienza i Pe\u00f1arroja<br \/>\n<strong>Editorial:<\/strong>\u00a0L&#8217;Oronella (Valencia)<br \/>\n<strong>Colecci\u00f3:<\/strong>\u00a0Els Fanals de la Terra, n\u00ba 6<br \/>\n<strong>Any:<\/strong>\u00a02003<br \/>\n<strong>Idioma:<\/strong> Valenci\u00e0<br \/>\n<strong>ISBN:\u00a0<\/strong>848973741X<br \/>\n<strong>P\u00e0gines:<\/strong>\u00a0117 p\u00e0gines[\/vc_column_text][\/vc_column][\/vc_row]\n","protected":false},"excerpt":{"rendered":"<p>[vc_row type=&#8221;full_width_content&#8221; full_screen_row_position=&#8221;middle&#8221; bg_image=&#8221;8350&#8243; bg_position=&#8221;center center&#8221; bg_repeat=&#8221;no-repeat&#8221; parallax_bg=&#8221;true&#8221; parallax_bg_speed=&#8221;medium&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; top_padding=&#8221;200&#8243; bottom_padding=&#8221;200&#8243; overlay_strength=&#8221;0.3&#8243; shape_divider_position=&#8221;bottom&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;padding-10-percent&#8221; column_padding_position=&#8221;left-right&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_link_target=&#8221;_self&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_row_inner equal_height=&#8221;yes&#8221; content_placement=&#8221;middle&#8221; column_margin=&#8221;default&#8221; text_align=&#8221;left&#8221;][vc_column_inner column_padding=&#8221;padding-5-percent&#8221; column_padding_position=&#8221;all&#8221; background_color=&#8221;#1d0e00&#8243; background_color_opacity=&#8221;0.6&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; width=&#8221;2\/3&#8243; tablet_width_inherit=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_custom_heading text=&#8221;Bibliografia&#8221; font_container=&#8221;tag:h1|text_align:left|color:%23ffffff&#8221; use_theme_fonts=&#8221;yes&#8221;][vc_custom_heading text=&#8221;Llibres&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-9876","page","type-page","status-publish"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Bibliografia - Monasterio de Sant Jeroni de Cotalba<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cotalba.es\/val\/bibliografia\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bibliografia - Monasterio de Sant Jeroni de Cotalba\" \/>\n<meta property=\"og:description\" content=\"[vc_row type=&#8221;full_width_content&#8221; full_screen_row_position=&#8221;middle&#8221; bg_image=&#8221;8350&#8243; bg_position=&#8221;center center&#8221; bg_repeat=&#8221;no-repeat&#8221; parallax_bg=&#8221;true&#8221; parallax_bg_speed=&#8221;medium&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; top_padding=&#8221;200&#8243; bottom_padding=&#8221;200&#8243; overlay_strength=&#8221;0.3&#8243; shape_divider_position=&#8221;bottom&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;padding-10-percent&#8221; column_padding_position=&#8221;left-right&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_link_target=&#8221;_self&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_row_inner equal_height=&#8221;yes&#8221; content_placement=&#8221;middle&#8221; column_margin=&#8221;default&#8221; text_align=&#8221;left&#8221;][vc_column_inner column_padding=&#8221;padding-5-percent&#8221; column_padding_position=&#8221;all&#8221; background_color=&#8221;#1d0e00&#8243; background_color_opacity=&#8221;0.6&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; width=&#8221;2\/3&#8243; tablet_width_inherit=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_custom_heading text=&#8221;Bibliografia&#8221; font_container=&#8221;tag:h1|text_align:left|color:%23ffffff&#8221; use_theme_fonts=&#8221;yes&#8221;][vc_custom_heading text=&#8221;Llibres...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cotalba.es\/val\/bibliografia\/\" \/>\n<meta property=\"og:site_name\" content=\"Monasterio de Sant Jeroni de Cotalba\" \/>\n<meta property=\"article:modified_time\" content=\"2019-06-16T15:50:45+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"15 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cotalba.es\\\/val\\\/bibliografia\\\/\",\"url\":\"https:\\\/\\\/cotalba.es\\\/val\\\/bibliografia\\\/\",\"name\":\"Bibliografia - Monasterio de Sant Jeroni de Cotalba\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cotalba.es\\\/#website\"},\"datePublished\":\"2019-05-29T19:25:07+00:00\",\"dateModified\":\"2019-06-16T15:50:45+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cotalba.es\\\/val\\\/bibliografia\\\/#breadcrumb\"},\"inLanguage\":\"val\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cotalba.es\\\/val\\\/bibliografia\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cotalba.es\\\/val\\\/bibliografia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/cotalba.es\\\/val\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Bibliografia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cotalba.es\\\/#website\",\"url\":\"https:\\\/\\\/cotalba.es\\\/\",\"name\":\"Monasterio de Sant Jeroni de Cotalba\",\"description\":\"Monasterio de Sant Jeroni de Cotalba\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cotalba.es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"val\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Bibliografia - Monasterio de Sant Jeroni de Cotalba","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cotalba.es\/val\/bibliografia\/","og_locale":"en_US","og_type":"article","og_title":"Bibliografia - Monasterio de Sant Jeroni de Cotalba","og_description":"[vc_row type=&#8221;full_width_content&#8221; full_screen_row_position=&#8221;middle&#8221; bg_image=&#8221;8350&#8243; bg_position=&#8221;center center&#8221; bg_repeat=&#8221;no-repeat&#8221; parallax_bg=&#8221;true&#8221; parallax_bg_speed=&#8221;medium&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; top_padding=&#8221;200&#8243; bottom_padding=&#8221;200&#8243; overlay_strength=&#8221;0.3&#8243; shape_divider_position=&#8221;bottom&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;padding-10-percent&#8221; column_padding_position=&#8221;left-right&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_link_target=&#8221;_self&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_row_inner equal_height=&#8221;yes&#8221; content_placement=&#8221;middle&#8221; column_margin=&#8221;default&#8221; text_align=&#8221;left&#8221;][vc_column_inner column_padding=&#8221;padding-5-percent&#8221; column_padding_position=&#8221;all&#8221; background_color=&#8221;#1d0e00&#8243; background_color_opacity=&#8221;0.6&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; width=&#8221;2\/3&#8243; tablet_width_inherit=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_custom_heading text=&#8221;Bibliografia&#8221; font_container=&#8221;tag:h1|text_align:left|color:%23ffffff&#8221; use_theme_fonts=&#8221;yes&#8221;][vc_custom_heading text=&#8221;Llibres...","og_url":"https:\/\/cotalba.es\/val\/bibliografia\/","og_site_name":"Monasterio de Sant Jeroni de Cotalba","article_modified_time":"2019-06-16T15:50:45+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"15 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/cotalba.es\/val\/bibliografia\/","url":"https:\/\/cotalba.es\/val\/bibliografia\/","name":"Bibliografia - Monasterio de Sant Jeroni de Cotalba","isPartOf":{"@id":"https:\/\/cotalba.es\/#website"},"datePublished":"2019-05-29T19:25:07+00:00","dateModified":"2019-06-16T15:50:45+00:00","breadcrumb":{"@id":"https:\/\/cotalba.es\/val\/bibliografia\/#breadcrumb"},"inLanguage":"val","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cotalba.es\/val\/bibliografia\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/cotalba.es\/val\/bibliografia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/cotalba.es\/val\/"},{"@type":"ListItem","position":2,"name":"Bibliografia"}]},{"@type":"WebSite","@id":"https:\/\/cotalba.es\/#website","url":"https:\/\/cotalba.es\/","name":"Monasterio de Sant Jeroni de Cotalba","description":"Monasterio de Sant Jeroni de Cotalba","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cotalba.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"val"}]}},"_links":{"self":[{"href":"https:\/\/cotalba.es\/val\/wp-json\/wp\/v2\/pages\/9876","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cotalba.es\/val\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/cotalba.es\/val\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/cotalba.es\/val\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/cotalba.es\/val\/wp-json\/wp\/v2\/comments?post=9876"}],"version-history":[{"count":1,"href":"https:\/\/cotalba.es\/val\/wp-json\/wp\/v2\/pages\/9876\/revisions"}],"predecessor-version":[{"id":9877,"href":"https:\/\/cotalba.es\/val\/wp-json\/wp\/v2\/pages\/9876\/revisions\/9877"}],"wp:attachment":[{"href":"https:\/\/cotalba.es\/val\/wp-json\/wp\/v2\/media?parent=9876"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}